{"id":74,"count":1,"description":"","link":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/","name":"Lights on For Safety","slug":"lights-on-for-safety","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lights on For Safety Archives - Dunwoody College News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lights on For Safety Archives - Dunwoody College News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/\" \/>\n<meta property=\"og:site_name\" content=\"Dunwoody College News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@dunwoodycollege\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/tag\\\/lights-on-for-safety\\\/\",\"url\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/tag\\\/lights-on-for-safety\\\/\",\"name\":\"Lights on For Safety Archives - Dunwoody College News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/tag\\\/lights-on-for-safety\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/tag\\\/lights-on-for-safety\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lights on For Safety\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/\",\"name\":\"Dunwoody College News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dunwoody.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lights on For Safety Archives - Dunwoody College News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/","og_locale":"en_US","og_type":"article","og_title":"Lights on For Safety Archives - Dunwoody College News","og_url":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/","og_site_name":"Dunwoody College News","twitter_card":"summary_large_image","twitter_site":"@dunwoodycollege","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/","url":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/","name":"Lights on For Safety Archives - Dunwoody College News","isPartOf":{"@id":"https:\/\/dunwoody.edu\/news\/#website"},"breadcrumb":{"@id":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dunwoody.edu\/news\/tag\/lights-on-for-safety\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dunwoody.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Lights on For Safety"}]},{"@type":"WebSite","@id":"https:\/\/dunwoody.edu\/news\/#website","url":"https:\/\/dunwoody.edu\/news\/","name":"Dunwoody College News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dunwoody.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dunwoody.edu\/news\/wp-json\/wp\/v2\/tags\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dunwoody.edu\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dunwoody.edu\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dunwoody.edu\/news\/wp-json\/wp\/v2\/posts?tags=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}